{"id":1936549,"date":"2026-05-29T15:03:34","date_gmt":"2026-05-29T13:03:34","guid":{"rendered":"https:\/\/visit-lakemaggiore.com\/?p=1936549"},"modified":"2026-07-14T16:18:13","modified_gmt":"2026-07-14T14:18:13","slug":"kinder-0-2-alto-lago","status":"publish","type":"post","link":"https:\/\/visit-lakemaggiore.com\/de\/kinder-0-2-alto-lago\/","title":{"rendered":"KINDER 0-2 &#8211; ALTO LAGO"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[MadeepStructureData id=&#8220;21&#8243;  price=&#8220;0.00&#8243; ]<\/p>\n<p>[vc_row full_width=&#8220;stretch_row&#8220; css=&#8220;.vc_custom_1721389530686{padding-top: 50px !important;padding-bottom: 50px !important;background-color: rgba(98,170,193,0.1) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;*background-color: rgb(98,170,193) !important;}&#8220; el_id=&#8220;struttura&#8220;][vc_column css_animation=&#8220;fadeInLeft&#8220; width=&#8220;2\/3&#8243; el_id=&#8220;descrizione&#8220;][vc_single_image source=&#8220;featured_image&#8220; img_size=&#8220;full&#8220; alignment=&#8220;center&#8220; css=&#8220;&#8220;][vc_custom_heading text=&#8220;ALTO LAGO RIDOTTO 0_2&#8243; font_container=&#8220;tag:h1|text_align:left|color:%233063ab&#8220; use_theme_fonts=&#8220;yes&#8220; css=&#8220;&#8220;][vc_custom_heading text=&#8220;Entdecken Sie den Lago Maggiore mit diesem Spezialticket!<br \/>\nDie Freikarte gilt f\u00fcr Kinder im Alter von 0 bis 2 Jahren. Achtung: Die Tickets sind nicht erstattungsf\u00e4hig!<\/p>\n<p>Maggiore Centro Alto Lago beinhaltet:<br \/>\n&#8211; Schiffstageskarte f\u00fcr die Strecke Cannero-Luino-Maccagno-Cannobio (Navigazione Lago Maggiore)<br \/>\n&#8211; Eintritt zu den Castelli di Cannero (+ Hin- und R\u00fcckfahrt mit dem Motorboot ab Cannero)<br \/>\n&#8211; Mittagessen mit festem Men\u00fc im Restaurant I Castelli (Hauptgericht und Dessert, inklusive Wasser und Kaffee)<\/p>\n<p>E-Mail: info@consorzio-maggiore.eu<br \/>\nWhatsApp: +39 3713705596&#8243; font_container=&#8220;tag:h4|text_align:left|color:%23555555&#8243; use_theme_fonts=&#8220;yes&#8220; css=&#8220;&#8220;][vc_column_text css=&#8220;&#8220;]Das Ticket Maggiore Centro Alto Lago erm\u00f6glicht Ihnen einen Tagesausflug mit einem Freifahrt-Ticket zwischen Cannero Riviera, Luino, Maccagno und Cannobio. Im Ticket enthalten ist au\u00dferdem der Eintritt zu den Castelli di Cannero (inklusive Bootstransfer mit dem Motorboot ab Cannero) sowie ein Mittagessen mit lokalen Spezialit\u00e4ten im Restaurant I Castelli in Cannero.[\/vc_column_text][vc_custom_heading text=&#8220;Bedingungen f\u00fcr den R\u00fccktritt&#8220; font_container=&#8220;tag:h5|text_align:left|color:%23555555&#8243; use_theme_fonts=&#8220;yes&#8220; css=&#8220;&#8220; el_class=&#8220;Bedingungen f\u00fcr den R\u00fccktritt&#8220;][vc_column_text css=&#8220;&#8220; el_class=&#8220;dettagli Tickets k\u00f6nnen nach Abschluss des Kaufs nicht mehr ge\u00e4ndert oder erstattet werden.&#8220;]Tickets k\u00f6nnen nach Abschluss des Kaufs nicht mehr ge\u00e4ndert oder erstattet werden.[\/vc_column_text][vc_custom_heading text=&#8220;Was ist enthalten&#8220; font_container=&#8220;tag:h5|text_align:left|color:%23555555&#8243; use_theme_fonts=&#8220;yes&#8220; css=&#8220;&#8220; el_class=&#8220;Was ist enthalten&#8220;][vc_column_text css=&#8220;&#8220; el_class=&#8220;dettagli &#8211; Schiffstageskarte f\u00fcr die Strecke Cannero-Luino-Maccagno-Cannobio (Navigazione Lago Maggiore)<br \/>\n&#8211; Eintritt zu den Castelli di Cannero (+ Hin- und R\u00fcckfahrt mit dem Motorboot ab Cannero)<br \/>\n&#8211; Mittagessen mit festem Men\u00fc im Restaurant I Castelli (Hauptgericht und Dessert, inklusive Wasser und Kaffee)&#8220;]- Schiffstageskarte f\u00fcr die Strecke Cannero-Luino-Maccagno-Cannobio (Navigazione Lago Maggiore)<br \/>\n&#8211; Eintritt zu den Castelli di Cannero (+ Hin- und R\u00fcckfahrt mit dem Motorboot ab Cannero)<br \/>\n&#8211; Mittagessen mit festem Men\u00fc im Restaurant I Castelli (Hauptgericht und Dessert, inklusive Wasser und Kaffee)[\/vc_column_text][vc_custom_heading text=&#8220;Was ist nicht enthalten&#8220; font_container=&#8220;tag:h5|text_align:left|color:%23555555&#8243; use_theme_fonts=&#8220;yes&#8220; css=&#8220;&#8220; el_class=&#8220;Was ist nicht enthalten&#8220;][vc_column_text css=&#8220;&#8220; el_class=&#8220;dettagli Alles, was nicht ausdr\u00fccklich angegeben ist.&#8220;]Alles, was nicht ausdr\u00fccklich angegeben ist.[\/vc_column_text][vc_custom_heading text=&#8220;Gut Zu Wissen&#8220; font_container=&#8220;tag:h5|text_align:left|color:%23555555&#8243; use_theme_fonts=&#8220;yes&#8220; css=&#8220;&#8220; el_class=&#8220;Gut Zu Wissen&#8220;][vc_column_text css=&#8220;&#8220; el_class=&#8220;dettagli Die Tour dauert zwischen 5 und 6 Stunden und ist t\u00e4glich au\u00dfer an Feiertagen verf\u00fcgbar.<br \/>\nDas Erlebnis ist f\u00fcr Personen mit eingeschr\u00e4nkter Mobilit\u00e4t nicht zug\u00e4nglich.<\/p>\n<p>Das Mittagessen im Restaurant I Castelli in Cannero findet von 12:00 bis 14:00 Uhr statt.<br \/>\nDas Mittagsmen\u00fc ist festgelegt und umfasst einen Hauptgang und ein Dessert, einschlie\u00dflich Wasser und Kaffee*.<\/p>\n<p>Frische Tortelli mit Ricotta und Zitronen von der Riviera, dazu kurz angebratenes Gem\u00fcse und H\u00f6hlenpilze.<\/p>\n<p>Panna Cotta mit Himbeeren.<\/p>\n<p>Kinder bis einschlie\u00dflich 2 Jahre erhalten freien Eintritt (f\u00fcr sie ist kein Mittagessen vorgesehen). Alle zus\u00e4tzlichen Speisen oder Getr\u00e4nke, die von Kindern oder Erwachsenen konsumiert werden, sind direkt im Restaurant zu bezahlen.<\/p>\n<p>*Bitte pr\u00fcfen Sie die Verf\u00fcgbarkeit des Mittagessens VOR dem Kauf Ihres Tickets mit uns. Nach der Buchung senden wir Ihnen einen Gutschein zu, den Sie dem Restaurantpersonal vorlegen m\u00fcssen, um die Leistung in Anspruch zu nehmen. F\u00fcr Informationen zu m\u00f6glichen Allergenen kontaktieren Sie uns bitte per E-Mail oder WhatsApp.<\/p>\n<p>Die Burgen von Cannero sind t\u00e4glich ge\u00f6ffnet. Um sie zu erreichen, muss das daf\u00fcr vorgesehene Motorboot genutzt werden, das um 9:45 Uhr, 11:45 Uhr, 13:45 Uhr oder 15:45 Uhr in der Via delle Magnolie ablegt. Die Besichtigung dauert genau eine Stunde; anschlie\u00dfend bringt Sie das Motorboot zur\u00fcck nach Cannero.<\/p>\n<p>Die Tour ist selbstgef\u00fchrt*: Wir empfehlen, den Audioguide f\u00fcr die Besichtigung der Burgen von Cannero herunterzuladen, der bei Google Play und im App Store verf\u00fcgbar ist. Kopfh\u00f6rer oder Ohrh\u00f6rer m\u00fcssen von den G\u00e4sten selbst mitgebracht werden. Haustiere sind nicht erlaubt.<\/p>\n<p>*Auf Anfrage kann Sie ein pers\u00f6nlicher Fremdenf\u00fchrer w\u00e4hrend der Tour begleiten. F\u00fcr weitere Informationen kontaktieren Sie uns bitte per E-Mail (info@consorzio-maggiore.eu(mailto:info@consorzio-maggiore.eu)) oder per WhatsApp (+39 371 370 5596).&#8220;]Die Tour dauert zwischen 5 und 6 Stunden und ist t\u00e4glich au\u00dfer an Feiertagen verf\u00fcgbar.<br \/>\nDas Erlebnis ist f\u00fcr Personen mit eingeschr\u00e4nkter Mobilit\u00e4t nicht zug\u00e4nglich.<\/p>\n<p>Das Mittagessen im Restaurant I Castelli in Cannero findet von 12:00 bis 14:00 Uhr statt.<br \/>\nDas Mittagsmen\u00fc ist festgelegt und umfasst einen Hauptgang und ein Dessert, einschlie\u00dflich Wasser und Kaffee*.<\/p>\n<p>Frische Tortelli mit Ricotta und Zitronen von der Riviera, dazu kurz angebratenes Gem\u00fcse und H\u00f6hlenpilze.<\/p>\n<p>Panna Cotta mit Himbeeren.<\/p>\n<p>Kinder bis einschlie\u00dflich 2 Jahre erhalten freien Eintritt (f\u00fcr sie ist kein Mittagessen vorgesehen). Alle zus\u00e4tzlichen Speisen oder Getr\u00e4nke, die von Kindern oder Erwachsenen konsumiert werden, sind direkt im Restaurant zu bezahlen.<\/p>\n<p>*Bitte pr\u00fcfen Sie die Verf\u00fcgbarkeit des Mittagessens VOR dem Kauf Ihres Tickets mit uns. Nach der Buchung senden wir Ihnen einen Gutschein zu, den Sie dem Restaurantpersonal vorlegen m\u00fcssen, um die Leistung in Anspruch zu nehmen. F\u00fcr Informationen zu m\u00f6glichen Allergenen kontaktieren Sie uns bitte per E-Mail oder WhatsApp.<\/p>\n<p>Die Burgen von Cannero sind t\u00e4glich ge\u00f6ffnet. Um sie zu erreichen, muss das daf\u00fcr vorgesehene Motorboot genutzt werden, das um 9:45 Uhr, 11:45 Uhr, 13:45 Uhr oder 15:45 Uhr in der Via delle Magnolie ablegt. Die Besichtigung dauert genau eine Stunde; anschlie\u00dfend bringt Sie das Motorboot zur\u00fcck nach Cannero.<\/p>\n<p>Die Tour ist selbstgef\u00fchrt*: Wir empfehlen, den Audioguide f\u00fcr die Besichtigung der Burgen von Cannero herunterzuladen, der bei Google Play und im App Store verf\u00fcgbar ist. Kopfh\u00f6rer oder Ohrh\u00f6rer m\u00fcssen von den G\u00e4sten selbst mitgebracht werden. Haustiere sind nicht erlaubt.<\/p>\n<p>*Auf Anfrage kann Sie ein pers\u00f6nlicher Fremdenf\u00fchrer w\u00e4hrend der Tour begleiten. F\u00fcr weitere Informationen kontaktieren Sie uns bitte per E-Mail (info@consorzio-maggiore.eu(mailto:info@consorzio-maggiore.eu)) oder per WhatsApp (+39 371 370 5596).[\/vc_column_text][\/vc_column][vc_column css_animation=&#8220;fadeInRightBig&#8220; width=&#8220;1\/3&#8243; el_id=&#8220;dati&#8220;][vc_custom_heading text=&#8220;Veranstaltungsort&#8220; font_container=&#8220;tag:h4|text_align:left|color:%233063ab&#8220; use_theme_fonts=&#8220;yes&#8220; css=&#8220;&#8220;][vc_goo_maps location=&#8220;Viale delle Magnolie, 8, Cannero Riviera&#8220; height=&#8220;250&#8243; zoom=&#8220;17&#8243; css=&#8220;.vc_custom_1781168839743{margin-bottom: 15px !important;}&#8220;][vc_custom_heading text=&#8220;Viale delle Magnolie, 8, Cannero Riviera&#8220; font_container=&#8220;tag:h5|text_align:left|color:%23555555&#8243; use_theme_fonts=&#8220;yes&#8220; css=&#8220;&#8220;][vc_custom_heading text=&#8220;Treffpunkt&#8220; font_container=&#8220;tag:h4|text_align:left|color:%233063ab&#8220; use_theme_fonts=&#8220;yes&#8220; css=&#8220;&#8220;][vc_goo_maps location=&#8220;&#8220; height=&#8220;250&#8243; zoom=&#8220;17&#8243; css=&#8220;.vc_custom_1781168835123{margin-bottom: 15px !important;}&#8220;][vc_custom_heading text=&#8220;, &#8220; font_container=&#8220;tag:h5|text_align:left|color:%23555555&#8243; use_theme_fonts=&#8220;yes&#8220; css=&#8220;&#8220;][vc_btn title=&#8220;Preise &amp; Reservierungen&#8220; shape=&#8220;square&#8220; color=&#8220;orange&#8220; align=&#8220;left&#8220; css=&#8220;&#8220; link=&#8220;url:http%3A%2F%2Fvisit-lakemaggiore.com\/de\/booking-erleben\/?channelid=685&amp;ecomid=3771&amp;serviceid=21&#8243;][vc_empty_space height=&#8220;30px&#8220;][vc_row_inner equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220;][vc_column_inner width=&#8220;2\/3&#8243;][vc_custom_heading text=&#8220;Brauchen Sie Informationen dazu?&#8220; font_container=&#8220;tag:h4|text_align:left|color:%233063ab&#8220; use_theme_fonts=&#8220;yes&#8220; css=&#8220;&#8220;][\/vc_column_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_icon icon_fontawesome=&#8220;fa fa-brands fa-whatsapp&#8220; color=&#8220;custom&#8220; size=&#8220;lg&#8220; align=&#8220;center&#8220; css=&#8220;&#8220; custom_color=&#8220;#F48B39&#8243; link=&#8220;url:https%3A%2F%2Fwa.me%2F393713705596|target:_blank&#8220; el_id=&#8220;whatsapp-call&#8220;][\/vc_column_inner][\/vc_row_inner]<style id=\"wpforms-css-vars-1349906\">\n\t\t\t\t#wpforms-1349906 {\n\t\t\t\t--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-1349906\"><form id=\"wpforms-form-1349906\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"1349906\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/de\/wp-json\/wp\/v2\/posts\/1936549\" data-token=\"cb670fbade19f4c51a718d8d97042462\" data-token-time=\"1784155895\"><noscript class=\"wpforms-error-noscript\">Bitte aktiviere JavaScript in deinem Browser, um dieses Formular fertigzustellen.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Bitte aktiviere JavaScript in deinem Browser, um dieses Formular fertigzustellen.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-1349906-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-type=\"name\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1349906-field_1\" aria-hidden=\"false\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-1349906-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"Name\" aria-errormessage=\"wpforms-1349906-field_1-error\" required><\/div><div id=\"wpforms-1349906-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1349906-field_2\" aria-hidden=\"false\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-1349906-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"Email\" spellcheck=\"false\" aria-errormessage=\"wpforms-1349906-field_2-error\" required><\/div><div id=\"wpforms-1349906-field_5-container\" class=\"wpforms-field wpforms-field-phone\" data-field-type=\"phone\" data-field-id=\"5\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1349906-field_5\" aria-hidden=\"false\">Telefon <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-1349906-field_5\" class=\"wpforms-field-large wpforms-field-required\" data-rule-int-phone-field=\"true\" name=\"wpforms[fields][5]\" placeholder=\"Telefon\" aria-label=\"Telefon\" aria-errormessage=\"wpforms-1349906-field_5-error\" required><\/div><div id=\"wpforms-1349906-field_3-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-type=\"textarea\" data-field-id=\"3\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1349906-field_3\" aria-hidden=\"false\">Nachricht<\/label><textarea id=\"wpforms-1349906-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" placeholder=\"Nachricht\" aria-errormessage=\"wpforms-1349906-field_3-error\" ><\/textarea><\/div><div id=\"wpforms-1349906-field_4-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"4\"><fieldset><legend class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">Privacy Policy <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-1349906-field_4\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-1349906-field_4_1\" name=\"wpforms[fields][4][]\" value=\"Ich habe die &lt;a target=&quot;_blank&quot; href=&quot;https:\/\/visit-lakemaggiore.com\/de\/privacy-policy\/&quot;&gt;Bestimmungen zur Speicherung&lt;\/a&gt; und Nutzung meiner Daten gelesen und bin damit einverstanden\" aria-errormessage=\"wpforms-1349906-field_4_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-1349906-field_4_1\">Ich habe die <a target=\"_blank\" href=\"https:\/\/visit-lakemaggiore.com\/de\/privacy-policy\/\">Bestimmungen zur Speicherung<\/a> und Nutzung meiner Daten gelesen und bin damit einverstanden<\/label><\/li><\/ul><\/fieldset><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"1349906\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/visit-lakemaggiore.com\/de\/wp-json\/wp\/v2\/posts\/1936549\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-1349906\" class=\"wpforms-submit\" data-alt-text=\"Senden...\" data-submit-text=\"Senden\" aria-live=\"assertive\" value=\"wpforms-submit\">Senden<\/button><img decoding=\"async\" src=\"https:\/\/visit-lakemaggiore.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Wird geladen\"><\/div><\/form><\/div>  <!-- .wpforms-container -->[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Entdecken Sie den Lago Maggiore mit diesem Spezialticket!<br \/>\nDie Freikarte gilt f\u00fcr Kinder im Alter von 0 bis 2 Jahren. Achtung: Die Tickets sind nicht erstattungsf\u00e4hig!<\/p>\n<p>Maggiore Centro Alto Lago beinhaltet:<br \/>\n&#8211; Schiffstageskarte f\u00fcr die Strecke Cannero-Luino-Maccagno-Cannobio (Navigazione Lago Maggiore)<br \/>\n&#8211; Eintritt zu den Castelli di Cannero (+ Hin- und R\u00fcckfahrt mit dem Motorboot ab Cannero)<br \/>\n&#8211; Mittagessen mit festem Men\u00fc im Restaurant I Castelli (Hauptgericht und Dessert, inklusive Wasser und Kaffee)<\/p>\n<p>E-Mail: info@consorzio-maggiore.eu<br \/>\nWhatsApp: +39 3713705596<\/p>\n","protected":false},"author":10,"featured_media":1960220,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[357],"tags":[1280,1342,1716],"class_list":["post-1936549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esperienze-de","tag-enogastronomia-esperienze-de","tag-arte-cultura-de","tag-maggiore-centro-alto-lago"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KINDER 0-2 - ALTO LAGO - Lago Maggiore Booking<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visit-lakemaggiore.com\/ticket-ridotto-0-2-alto-lago\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KINDER 0-2 - ALTO LAGO - Lago Maggiore Booking\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie den Lago Maggiore mit diesem Spezialticket! Die Freikarte gilt f\u00fcr Kinder im Alter von 0 bis 2 Jahren. Achtung: Die Tickets sind nicht erstattungsf\u00e4hig! Maggiore Centro Alto Lago beinhaltet: - Schiffstageskarte f\u00fcr die Strecke Cannero-Luino-Maccagno-Cannobio (Navigazione Lago Maggiore) - Eintritt zu den Castelli di Cannero (+ Hin- und R\u00fcckfahrt mit dem Motorboot ab Cannero) - Mittagessen mit festem Men\u00fc im Restaurant I Castelli (Hauptgericht und Dessert, inklusive Wasser und Kaffee) E-Mail: info@consorzio-maggiore.eu WhatsApp: +39 3713705596\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visit-lakemaggiore.com\/ticket-ridotto-0-2-alto-lago\/\" \/>\n<meta property=\"og:site_name\" content=\"Lago Maggiore Booking\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/consorziomaggiore\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-29T13:03:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T14:18:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visit-lakemaggiore.com\/wp-content\/uploads\/ec_service_3771_21-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gaia Di Sessa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gaia Di Sessa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/ticket-ridotto-0-2-alto-lago\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/ticket-ridotto-0-2-alto-lago\\\/\"},\"author\":{\"name\":\"Gaia Di Sessa\",\"@id\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/#\\\/schema\\\/person\\\/ddf34914d03bd2b02db690e6716426e8\"},\"headline\":\"KINDER 0-2 &#8211; ALTO LAGO\",\"datePublished\":\"2026-05-29T13:03:34+00:00\",\"dateModified\":\"2026-07-14T14:18:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/ticket-ridotto-0-2-alto-lago\\\/\"},\"wordCount\":1351,\"publisher\":{\"@id\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/ticket-ridotto-0-2-alto-lago\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/wp-content\\\/uploads\\\/ec_service_3771_21-2.jpg\",\"keywords\":[\"Enogastronomia Esperienze DE\",\"Arte Cultura DE\",\"Maggiore Centro Alto Lago\"],\"articleSection\":[\"Esperienze DE\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/ticket-ridotto-0-2-alto-lago\\\/\",\"url\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/ticket-ridotto-0-2-alto-lago\\\/\",\"name\":\"KINDER 0-2 - ALTO LAGO - Lago Maggiore Booking\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/ticket-ridotto-0-2-alto-lago\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/ticket-ridotto-0-2-alto-lago\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/wp-content\\\/uploads\\\/ec_service_3771_21-2.jpg\",\"datePublished\":\"2026-05-29T13:03:34+00:00\",\"dateModified\":\"2026-07-14T14:18:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/ticket-ridotto-0-2-alto-lago\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visit-lakemaggiore.com\\\/ticket-ridotto-0-2-alto-lago\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/ticket-ridotto-0-2-alto-lago\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/wp-content\\\/uploads\\\/ec_service_3771_21-2.jpg\",\"contentUrl\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/wp-content\\\/uploads\\\/ec_service_3771_21-2.jpg\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/ticket-ridotto-0-2-alto-lago\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KINDER 0-2 &#8211; ALTO LAGO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/#website\",\"url\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/\",\"name\":\"Lago Maggiore Booking\",\"description\":\"Portale Turistico\",\"publisher\":{\"@id\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/#organization\",\"name\":\"Lago Maggiore Booking\",\"url\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/wp-content\\\/uploads\\\/visit-lake-maggiore-logo.png\",\"contentUrl\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/wp-content\\\/uploads\\\/visit-lake-maggiore-logo.png\",\"width\":500,\"height\":194,\"caption\":\"Lago Maggiore Booking\"},\"image\":{\"@id\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/consorziomaggiore\",\"https:\\\/\\\/www.instagram.com\\\/consorziomaggiore\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC2R0AudHfLeA8Qj2iMTVIDA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/visit-lakemaggiore.com\\\/#\\\/schema\\\/person\\\/ddf34914d03bd2b02db690e6716426e8\",\"name\":\"Gaia Di Sessa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec2b29aa64aaf8336901e7be17e01d20ae444f83e97a2b3fb62c420f638ce0ef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec2b29aa64aaf8336901e7be17e01d20ae444f83e97a2b3fb62c420f638ce0ef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec2b29aa64aaf8336901e7be17e01d20ae444f83e97a2b3fb62c420f638ce0ef?s=96&d=mm&r=g\",\"caption\":\"Gaia Di Sessa\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KINDER 0-2 - ALTO LAGO - Lago Maggiore Booking","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visit-lakemaggiore.com\/ticket-ridotto-0-2-alto-lago\/","og_locale":"de_DE","og_type":"article","og_title":"KINDER 0-2 - ALTO LAGO - Lago Maggiore Booking","og_description":"Entdecken Sie den Lago Maggiore mit diesem Spezialticket! Die Freikarte gilt f\u00fcr Kinder im Alter von 0 bis 2 Jahren. Achtung: Die Tickets sind nicht erstattungsf\u00e4hig! Maggiore Centro Alto Lago beinhaltet: - Schiffstageskarte f\u00fcr die Strecke Cannero-Luino-Maccagno-Cannobio (Navigazione Lago Maggiore) - Eintritt zu den Castelli di Cannero (+ Hin- und R\u00fcckfahrt mit dem Motorboot ab Cannero) - Mittagessen mit festem Men\u00fc im Restaurant I Castelli (Hauptgericht und Dessert, inklusive Wasser und Kaffee) E-Mail: info@consorzio-maggiore.eu WhatsApp: +39 3713705596","og_url":"https:\/\/visit-lakemaggiore.com\/ticket-ridotto-0-2-alto-lago\/","og_site_name":"Lago Maggiore Booking","article_publisher":"https:\/\/www.facebook.com\/consorziomaggiore","article_published_time":"2026-05-29T13:03:34+00:00","article_modified_time":"2026-07-14T14:18:13+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/visit-lakemaggiore.com\/wp-content\/uploads\/ec_service_3771_21-2.jpg","type":"image\/jpeg"}],"author":"Gaia Di Sessa","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Gaia Di Sessa","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/visit-lakemaggiore.com\/ticket-ridotto-0-2-alto-lago\/#article","isPartOf":{"@id":"https:\/\/visit-lakemaggiore.com\/ticket-ridotto-0-2-alto-lago\/"},"author":{"name":"Gaia Di Sessa","@id":"https:\/\/visit-lakemaggiore.com\/#\/schema\/person\/ddf34914d03bd2b02db690e6716426e8"},"headline":"KINDER 0-2 &#8211; ALTO LAGO","datePublished":"2026-05-29T13:03:34+00:00","dateModified":"2026-07-14T14:18:13+00:00","mainEntityOfPage":{"@id":"https:\/\/visit-lakemaggiore.com\/ticket-ridotto-0-2-alto-lago\/"},"wordCount":1351,"publisher":{"@id":"https:\/\/visit-lakemaggiore.com\/#organization"},"image":{"@id":"https:\/\/visit-lakemaggiore.com\/ticket-ridotto-0-2-alto-lago\/#primaryimage"},"thumbnailUrl":"https:\/\/visit-lakemaggiore.com\/wp-content\/uploads\/ec_service_3771_21-2.jpg","keywords":["Enogastronomia Esperienze DE","Arte Cultura DE","Maggiore Centro Alto Lago"],"articleSection":["Esperienze DE"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/visit-lakemaggiore.com\/ticket-ridotto-0-2-alto-lago\/","url":"https:\/\/visit-lakemaggiore.com\/ticket-ridotto-0-2-alto-lago\/","name":"KINDER 0-2 - ALTO LAGO - Lago Maggiore Booking","isPartOf":{"@id":"https:\/\/visit-lakemaggiore.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visit-lakemaggiore.com\/ticket-ridotto-0-2-alto-lago\/#primaryimage"},"image":{"@id":"https:\/\/visit-lakemaggiore.com\/ticket-ridotto-0-2-alto-lago\/#primaryimage"},"thumbnailUrl":"https:\/\/visit-lakemaggiore.com\/wp-content\/uploads\/ec_service_3771_21-2.jpg","datePublished":"2026-05-29T13:03:34+00:00","dateModified":"2026-07-14T14:18:13+00:00","breadcrumb":{"@id":"https:\/\/visit-lakemaggiore.com\/ticket-ridotto-0-2-alto-lago\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visit-lakemaggiore.com\/ticket-ridotto-0-2-alto-lago\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/visit-lakemaggiore.com\/ticket-ridotto-0-2-alto-lago\/#primaryimage","url":"https:\/\/visit-lakemaggiore.com\/wp-content\/uploads\/ec_service_3771_21-2.jpg","contentUrl":"https:\/\/visit-lakemaggiore.com\/wp-content\/uploads\/ec_service_3771_21-2.jpg","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/visit-lakemaggiore.com\/ticket-ridotto-0-2-alto-lago\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/visit-lakemaggiore.com\/"},{"@type":"ListItem","position":2,"name":"KINDER 0-2 &#8211; ALTO LAGO"}]},{"@type":"WebSite","@id":"https:\/\/visit-lakemaggiore.com\/#website","url":"https:\/\/visit-lakemaggiore.com\/","name":"Lago Maggiore Booking","description":"Portale Turistico","publisher":{"@id":"https:\/\/visit-lakemaggiore.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visit-lakemaggiore.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/visit-lakemaggiore.com\/#organization","name":"Lago Maggiore Booking","url":"https:\/\/visit-lakemaggiore.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/visit-lakemaggiore.com\/#\/schema\/logo\/image\/","url":"https:\/\/visit-lakemaggiore.com\/wp-content\/uploads\/visit-lake-maggiore-logo.png","contentUrl":"https:\/\/visit-lakemaggiore.com\/wp-content\/uploads\/visit-lake-maggiore-logo.png","width":500,"height":194,"caption":"Lago Maggiore Booking"},"image":{"@id":"https:\/\/visit-lakemaggiore.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/consorziomaggiore","https:\/\/www.instagram.com\/consorziomaggiore\/","https:\/\/www.youtube.com\/channel\/UC2R0AudHfLeA8Qj2iMTVIDA"]},{"@type":"Person","@id":"https:\/\/visit-lakemaggiore.com\/#\/schema\/person\/ddf34914d03bd2b02db690e6716426e8","name":"Gaia Di Sessa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/ec2b29aa64aaf8336901e7be17e01d20ae444f83e97a2b3fb62c420f638ce0ef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ec2b29aa64aaf8336901e7be17e01d20ae444f83e97a2b3fb62c420f638ce0ef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ec2b29aa64aaf8336901e7be17e01d20ae444f83e97a2b3fb62c420f638ce0ef?s=96&d=mm&r=g","caption":"Gaia Di Sessa"}}]}},"_links":{"self":[{"href":"https:\/\/visit-lakemaggiore.com\/de\/wp-json\/wp\/v2\/posts\/1936549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit-lakemaggiore.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visit-lakemaggiore.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visit-lakemaggiore.com\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/visit-lakemaggiore.com\/de\/wp-json\/wp\/v2\/comments?post=1936549"}],"version-history":[{"count":57,"href":"https:\/\/visit-lakemaggiore.com\/de\/wp-json\/wp\/v2\/posts\/1936549\/revisions"}],"predecessor-version":[{"id":1960219,"href":"https:\/\/visit-lakemaggiore.com\/de\/wp-json\/wp\/v2\/posts\/1936549\/revisions\/1960219"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit-lakemaggiore.com\/de\/wp-json\/wp\/v2\/media\/1960220"}],"wp:attachment":[{"href":"https:\/\/visit-lakemaggiore.com\/de\/wp-json\/wp\/v2\/media?parent=1936549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit-lakemaggiore.com\/de\/wp-json\/wp\/v2\/categories?post=1936549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit-lakemaggiore.com\/de\/wp-json\/wp\/v2\/tags?post=1936549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}